{"id":1505,"date":"2026-05-01T09:20:34","date_gmt":"2026-05-01T12:20:34","guid":{"rendered":"https:\/\/masindustrias.com.ar\/mas-campo\/?p=1505"},"modified":"2026-05-01T09:20:35","modified_gmt":"2026-05-01T12:20:35","slug":"simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles","status":"publish","type":"post","link":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/","title":{"rendered":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo 20 de mayo de 2026, la ciudad de Santa Rosa, en la provincia de La Pampa, se convertir\u00e1 en el epicentro del conocimiento agron\u00f3mico con la realizaci\u00f3n del Simposio Regional Fertilidad 2026. El evento, que tendr\u00e1 lugar en el Hotel Mercure, es organizado conjuntamente por <strong>Fertilizar Asociaci\u00f3n Civil y la Facultad de Agronom\u00eda de la Universidad Nacional de La Pampa (UNLPam).<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La jornada contar\u00e1 con un nutrido Panel T\u00e9cnico dividido en cuatro m\u00f3dulos, donde destacados especialistas expondr\u00e1n resultados y estrategias innovadoras para optimizar la producci\u00f3n en el campo.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El bloque t\u00e9cnico iniciar\u00e1 con la intervenci\u00f3n del Dr. Diego Rotilli (FA UNLPam \u2013 Agroinnova), quien profundizar\u00e1 en la determinaci\u00f3n del rendimiento potencial de los cultivos de invierno, analizando variables como el agua, la radiaci\u00f3n y la temperatura. Su enfoque integrar\u00e1 <strong>el diagn\u00f3stico de demanda de nutrientes y un detallado an\u00e1lisis econ\u00f3mico basado en la relaci\u00f3n insumo-producto.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el Dr. Cristian \u00c1lvarez (INTA \u2013 FA UNLPam) abordar\u00e1 la nutrici\u00f3n balanceada como una herramienta fundamental para potenciar la productividad forrajera. <strong>\u00c1lvarez destacar\u00e1 c\u00f3mo la fertilizaci\u00f3n qu\u00edmica no solo mejora el rendimiento,<\/strong> sino que optimiza la condici\u00f3n f\u00edsica del suelo y la eficiencia en la cosecha de agua, un factor cr\u00edtico para las zonas con d\u00e9ficit h\u00eddrico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"720\" src=\"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Suelo-1024x720.webp\" alt=\"\" class=\"wp-image-1507\" srcset=\"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Suelo-1024x720.webp 1024w, https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Suelo-300x211.webp 300w, https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Suelo-768x540.webp 768w, https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Suelo.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada de la tarde estar\u00e1 centrada en los cultivos de verano. El Dr. Gabriel Esp\u00f3sito (UNRC) presentar\u00e1 estrategias de manejo nutricional para el ma\u00edz en ambientes semi\u00e1ridos y subh\u00famedos, <strong>analizando las brechas entre el rendimiento potencial y el real tanto en sistemas de riego como de secano.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la Dra. Mirian Barraco (INTA) disertar\u00e1 sobre la nutrici\u00f3n en soja y girasol. En el caso de la soja, pondr\u00e1 \u00e9nfasis en la inoculaci\u00f3n para la provisi\u00f3n de nitr\u00f3geno y la fertilizaci\u00f3n balanceada con f\u00f3sforo, azufre, calcio y boro. Para <strong>el girasol, el foco estar\u00e1 en la eficiencia de aplicaci\u00f3n de nitr\u00f3geno <\/strong>y otros micronutrientes para maximizar la respuesta productiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un espacio de referencia institucional y empresarial<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Simposio se consolida como un espacio de referencia para la sostenibilidad de los sistemas productivos en regiones semi\u00e1ridas. <strong>El evento cuenta con el respaldo del Ministerio de la Producci\u00f3n de La Pampa, el INTA, el CPIA, el CIALP y CREA.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el encuentro posee un fuerte apoyo del sector privado, con la participaci\u00f3n de empresas l\u00edderes como Cofco, Amaggi, Bunge, ACA, Spraytec, YARA, Lartirigoyen, Profertil, Esagro, Fedea, Grupo Quem\u00fa, Men\u00e9ndez Cia, Nutrien AG Solutions y CURY.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta colaboraci\u00f3n entre la academia, las instituciones t\u00e9cnicas y la industria <strong>busca brindar a los asistentes informaci\u00f3n actualizada para mejorar la eficiencia del uso de nutrientes y del agua en la regi\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada tiene cupos limitados y requiere de pre inscripci\u00f3n en el siguiente link: <a href=\"https:\/\/www.eventbrite.com.ar\/e\/simposio-regional-fertilidad-2026-tickets-1985938828496?aff=oddtdtcreator&amp;keep_tld=true\">Simposio Regional Fertilidad 2026.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento se desarrollar\u00e1 el venidero mi\u00e9rcoles 20. Los especialistas expondr\u00e1n resultados y estrategias innovadoras para optimizar la producci\u00f3n en el campo.<\/p>\n","protected":false},"author":1,"featured_media":1506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[220,17],"class_list":["post-1505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","tag-fertilizacion","tag-suelos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles\" \/>\n<meta property=\"og:description\" content=\"El evento se desarrollar\u00e1 el venidero mi\u00e9rcoles 20. Los especialistas expondr\u00e1n resultados y estrategias innovadoras para optimizar la producci\u00f3n en el campo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1s Campo\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-01T12:20:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T12:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n M\u00e1s Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n M\u00e1s Campo\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#\\\/schema\\\/person\\\/628d97aab99dad3321861bf7ce753fd1\"},\"headline\":\"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles\",\"datePublished\":\"2026-05-01T12:20:34+00:00\",\"dateModified\":\"2026-05-01T12:20:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/\"},\"wordCount\":507,\"publisher\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Fertilizar.jpg\",\"keywords\":[\"Fertilizaci\u00f3n\",\"Suelos\"],\"articleSection\":[\"Agricultura\"],\"inLanguage\":\"es-AR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/\",\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/\",\"name\":\"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Fertilizar.jpg\",\"datePublished\":\"2026-05-01T12:20:34+00:00\",\"dateModified\":\"2026-05-01T12:20:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Fertilizar.jpg\",\"contentUrl\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Fertilizar.jpg\",\"width\":1200,\"height\":675,\"caption\":\"La fertilizaci\u00f3n qu\u00edmica no solo mejora el rendimiento, sino que optimiza la condici\u00f3n f\u00edsica del suelo.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/2026\\\/05\\\/01\\\/agricultura\\\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#website\",\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/\",\"name\":\"M\u00e1s Campo\",\"description\":\"Actualidad del Campo y del Sector Agropecuario de Bah\u00eda Blanca y la Regi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#organization\"},\"alternateName\":\"M\u00e1s Campo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#organization\",\"name\":\"M\u00e1s Campo\",\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/mas-campo-noticias-agicolas.svg\",\"contentUrl\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/mas-campo-noticias-agicolas.svg\",\"width\":455,\"height\":69,\"caption\":\"M\u00e1s Campo\"},\"image\":{\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/#\\\/schema\\\/person\\\/628d97aab99dad3321861bf7ce753fd1\",\"name\":\"Redacci\u00f3n M\u00e1s Campo\",\"description\":\"Redacci\u00f3n de M\u00e1s Campo, el medio de comunicaci\u00f3n de Bah\u00eda Blanca, el sudoeste de la provincia de Buenos Aires y la regi\u00f3n, especializado en ganader\u00eda y agricultura.\",\"sameAs\":[\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\"],\"url\":\"https:\\\/\\\/masindustrias.com.ar\\\/mas-campo\\\/author\\\/mas-campo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/","og_locale":"es_ES","og_type":"article","og_title":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles","og_description":"El evento se desarrollar\u00e1 el venidero mi\u00e9rcoles 20. Los especialistas expondr\u00e1n resultados y estrategias innovadoras para optimizar la producci\u00f3n en el campo.","og_url":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/","og_site_name":"M\u00e1s Campo","article_published_time":"2026-05-01T12:20:34+00:00","article_modified_time":"2026-05-01T12:20:35+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n M\u00e1s Campo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#article","isPartOf":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/"},"author":{"name":"Redacci\u00f3n M\u00e1s Campo","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#\/schema\/person\/628d97aab99dad3321861bf7ce753fd1"},"headline":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles","datePublished":"2026-05-01T12:20:34+00:00","dateModified":"2026-05-01T12:20:35+00:00","mainEntityOfPage":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/"},"wordCount":507,"publisher":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#organization"},"image":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#primaryimage"},"thumbnailUrl":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg","keywords":["Fertilizaci\u00f3n","Suelos"],"articleSection":["Agricultura"],"inLanguage":"es-AR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#organization"}},{"@type":"WebPage","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/","url":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/","name":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles","isPartOf":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#primaryimage"},"image":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#primaryimage"},"thumbnailUrl":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg","datePublished":"2026-05-01T12:20:34+00:00","dateModified":"2026-05-01T12:20:35+00:00","breadcrumb":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#primaryimage","url":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg","contentUrl":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2026\/04\/Fertilizar.jpg","width":1200,"height":675,"caption":"La fertilizaci\u00f3n qu\u00edmica no solo mejora el rendimiento, sino que optimiza la condici\u00f3n f\u00edsica del suelo."},{"@type":"BreadcrumbList","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/2026\/05\/01\/agricultura\/simposio-regional-fertilidad-2026-en-santa-rosa-se-debatira-sobre-nutricion-de-cultivos-sostenibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/masindustrias.com.ar\/mas-campo\/"},{"@type":"ListItem","position":2,"name":"Simposio Regional Fertilidad 2026: en Santa Rosa se debatir\u00e1 sobre nutrici\u00f3n de cultivos sostenibles"}]},{"@type":"WebSite","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#website","url":"https:\/\/masindustrias.com.ar\/mas-campo\/","name":"M\u00e1s Campo","description":"Actualidad del Campo y del Sector Agropecuario de Bah\u00eda Blanca y la Regi\u00f3n","publisher":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#organization"},"alternateName":"M\u00e1s Campo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masindustrias.com.ar\/mas-campo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#organization","name":"M\u00e1s Campo","url":"https:\/\/masindustrias.com.ar\/mas-campo\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#\/schema\/logo\/image\/","url":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2025\/08\/mas-campo-noticias-agicolas.svg","contentUrl":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-content\/uploads\/2025\/08\/mas-campo-noticias-agicolas.svg","width":455,"height":69,"caption":"M\u00e1s Campo"},"image":{"@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/masindustrias.com.ar\/mas-campo\/#\/schema\/person\/628d97aab99dad3321861bf7ce753fd1","name":"Redacci\u00f3n M\u00e1s Campo","description":"Redacci\u00f3n de M\u00e1s Campo, el medio de comunicaci\u00f3n de Bah\u00eda Blanca, el sudoeste de la provincia de Buenos Aires y la regi\u00f3n, especializado en ganader\u00eda y agricultura.","sameAs":["https:\/\/masindustrias.com.ar\/mas-campo"],"url":"https:\/\/masindustrias.com.ar\/mas-campo\/author\/mas-campo\/"}]}},"_links":{"self":[{"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/posts\/1505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/comments?post=1505"}],"version-history":[{"count":1,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/posts\/1505\/revisions"}],"predecessor-version":[{"id":1508,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/posts\/1505\/revisions\/1508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/media\/1506"}],"wp:attachment":[{"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/media?parent=1505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/categories?post=1505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masindustrias.com.ar\/mas-campo\/wp-json\/wp\/v2\/tags?post=1505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}